{"id":1857,"date":"2022-06-14T14:03:47","date_gmt":"2022-06-14T14:03:47","guid":{"rendered":"https:\/\/csiag.eu\/?p=1857"},"modified":"2024-04-24T17:54:00","modified_gmt":"2024-04-24T17:54:00","slug":"sostituisci-la-toilette-a-cassetta-thetford-con-una-toilette-separata-separata","status":"publish","type":"post","link":"https:\/\/csiag.eu\/it\/blog\/2022\/06\/14\/austausch-thetford-kassetten-toilette-gegen-separette-trenntoilette\/","title":{"rendered":"Sostituzione della toilette a cassetta Thetford con una toilette separabile Separatte"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Momento della lettura<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minuti<\/span><\/span>\n<p class=\"wp-block-paragraph\">Tutti conoscono la toilette a cassetta Thetford, il problema dello smaltimento, le cassette troppo piccole, i pi\u00f9 audaci ne acquistano addirittura diverse per allungare gli intervalli di smaltimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La toilette separata promette soluzioni semplici e inodore, facile sostituzione e poca manutenzione. Alcuni sono dotati di un agitatore meccanico ad azionamento manuale. Anche in questo caso vengono offerti set semplici, quindi economici, composti da due contenitori e una parte stampata per separare feci e urina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il prezzo dei servizi igienici oscilla tra i 150 ei 2.000 euro circa, a seconda della complessit\u00e0 e della finitura pi\u00f9 o meno esclusiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alla fine, il tuo portafoglio e i tuoi requisiti determineranno la tua scelta finale. Nella maggior parte dei casi si trova la media aurea, ovvero circa 700 euro <a href=\"https:\/\/www.amazon.de\/Separett-Winzige-wasserlose-Urin-Umlenktoilette-Urinbeh%C3%A4lter\/dp\/B08SGP83GY\/ref=sr_1_8?__mk_de_DE=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=150YRP9VU7TY6&amp;keywords=separett&amp;qid=1655215157&amp;sprefix=separate%2Caps%2C112&amp;sr=8-8\" target=\"_blank\" rel=\"noreferrer noopener\">Separato Piccolo<\/a> con contenitore per urina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperienze dalla pratica \u2013 finora dopo circa sei mesi:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comfort \u2013 Ti siedi molto comodamente, come a casa<\/li>\n\n\n\n<li>Sviluppo di odori \u2013 n\u00e9 l\u2019urina n\u00e9 le feci lasciano odori, nemmeno in un lucernario con un ventilatore acceso; Esternamente si potrebbero avvertire odori dovuti al flusso di ventilazione verso l&#039;esterno.<\/li>\n\n\n\n<li>Cura: \u00e8 sufficiente una carta igienica con EM (Microrganismi Effettivi) per pulire le parti visibili dopo ogni utilizzo. NON spruzzare la soluzione EM nel contenitore dell&#039;urina poich\u00e9 qualsiasi aggiunta di acqua all&#039;urina causer\u00e0 odore.<\/li>\n\n\n\n<li>Suggerimento: i sacchetti per rifiuti compostabili possono sciogliersi gi\u00e0 dopo sole tre settimane. Pertanto, per essere sicuri, nel contenitore dei rifiuti inserire prima un sacchetto per rifiuti convenzionale, poi il sacchetto compostabile. L&#039;umidit\u00e0 si diffonde anche dal sacchetto compostabile, depositandosi sotto forma di goccioline nel sacchetto dei rifiuti circostante. Il contenitore in quanto tale rimane esente da qualsiasi contaminazione.<\/li>\n\n\n\n<li>Il contenitore delle feci \u00e8 pieno dopo circa una settimana, il contenitore delle urine deve essere svuotato dopo 2-3 giorni (se utilizzato da 2 adulti).<\/li>\n\n\n\n<li>La ventola integrata e costantemente in funzione (1,6 W nominali 12 V) \u00e8 molto silenziosa e non si sente pi\u00f9 quando la porta della toilette \u00e8 chiusa.<\/li>\n\n\n\n<li>Quando il sedile del WC viene ripiegato per rimuovere il contenitore dell&#039;urina, i sassolini blu inseriti nel filtro dell&#039;urina cadono sempre sulle lamelle del contenitore dei rifiuti e si scoloriscono (ma possono essere facilmente rimossi senza lasciare residui).<br>In alternativa, stiamo attualmente testando pastiglie detergenti per WC che si dissolvono pi\u00f9 rapidamente e scompaiono nel serbatoio dell&#039;urina. Resta da vedere quale sia il loro effetto in termini di prevenzione dei calcoli urinari.<br><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;ampliamento dell&#039;unit\u00e0 Thetford \u00e8 stato completato in 20 minuti. Per i sistemi a pressione, assicurarsi di rilasciare preventivamente la pressione per evitare un allagamento limitato quando si scollega il tubo dell&#039;acqua del dispositivo di lavaggio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nicchia della parete viene chiusa con una lastra serigrafica da 10 mm, con il lato liscio rivolto verso l&#039;esterno. Chiusura ermetica con cucitura circonferenziale in silicone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;installazione del Separatte Tiny (<a href=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/07\/Separett-Tiny-Manual.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Istruzioni di installazione\/funzionamento<\/a>) si limita a due viti per il muro e tre per il fissaggio a pavimento, il collegamento per la ventilazione e il motore della ventola, che tra l&#039;altro \u00e8 abbastanza economico e silenzioso con 133 mA \/ 1,6 W.<br>Prima del definitivo avvitamento a parete e pavimento, consigliamo un giro di prova: la posizione \u00e8 adatta a tutte le eventualit\u00e0? In caso contrario, ora puoi correggerlo in una direzione o nell&#039;altra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il convogliamento dell&#039;aria di scarico richiede molto tempo se si desidera realizzarlo tramite lo sportello di servizio esistente e nelle vicinanze.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Sepaarette_Abluftfuehrung_2-768x1024.jpg\" alt=\"\" class=\"wp-image-1861\" srcset=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Sepaarette_Abluftfuehrung_2-768x1024.jpg 768w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Sepaarette_Abluftfuehrung_2-225x300.jpg 225w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Sepaarette_Abluftfuehrung_2.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Condotto dell&#039;aria di scarico con tubo flessibile DN50<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Il tubo di scarico compreso negli accessori \u00e8 tagliato a larghezza Separatte e dotato di angolo HT di 90\u00b0 DN50. A questo \u00e8 collegato il tubo flessibile, la cui estremit\u00e0 si trova in un cosiddetto adattatore in gomma <a href=\"https:\/\/www.amazon.de\/dp\/B010QLZ0CA\/ref=pe_27091401_487027711_TE_SCE_dp_1\" target=\"_blank\" rel=\"noreferrer noopener\">Adattatore combinato Crassus CKA<\/a> conduce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;adattatore \u00e8 accorciato su entrambi i lati. Il lato da 40 mm viene tagliato nella scanalatura centrale con un taglierino. La parte liscia da 70 mm viene separata dalla parte scanalata in corrispondenza della giunzione prevista allo stesso modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il foro nella piastra SD misura 76 mm (corrispondente alla punta esistente). Idealmente si fora dall&#039;esterno, con lo sportello di servizio chiuso, attraverso di esso e immediatamente attraverso la lastra serigrafica. Ci\u00f2 garantisce che entrambi i fori siano congruenti e che il condotto dell&#039;aria di scarico si adatti perfettamente.<br>La piastra serigrafica viene incollata dall&#039;interno in modo ermetico con silicone sulla parete laterale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La parte tagliata dell&#039;adattatore liscio viene spinta sopra l&#039;area scanalata e inserita nel foro della lastra serigrafica. Ora l&#039;estremit\u00e0 fissa e rastremata del tubo flessibile viene accorciata a circa 1 cm rimanente e inserita per circa due terzi dall&#039;interno nell&#039;adattatore di gomma preparato.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_offen-1024x768.jpg\" alt=\"\" class=\"wp-image-1863\" srcset=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_offen-1024x768.jpg 1024w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_offen-300x225.jpg 300w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_offen-768x576.jpg 768w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_offen.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Collegamento del tubo flessibile con lo sportello di servizio, oltre che esterno. Collegamento prelievo acqua<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Il foro nello sportello di servizio chiuso \u00e8 dotato di riduzione DN75\/50 <a href=\"https:\/\/www.amazon.de\/gp\/product\/B017Z9XX9S\/ref=ppx_yo_dt_b_asin_title_o00_s00?ie=UTF8&amp;psc=1\" target=\"_blank\" rel=\"noreferrer noopener\">Airfit7550IR<\/a>, che viene fissato tutt&#039;intorno con abbondante silicone nello sportello di servizio. La riduzione viene pressata saldamente sulla guarnizione in gomma montata nel piatto serigrafico e fissata tutt&#039;intorno con alcuni piccoli cunei nell&#039;apposita posizione centrale finch\u00e9 il silicone non si \u00e8 solidificato. Successivamente si rimuovono i cunei e si riempiono gli alveoli e le fughe circostanti con silicone e si liscia con acqua saponata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presa dell&#039;acqua ancora installata qui \u00e8 stata collegata al collegamento di scarico esistente della toilette Thetford. A tale scopo il tubo dell&#039;acqua esistente \u00e8 stato accorciato di conseguenza e collegato saldamente con un angolo di 90\u00b0 al collegamento della presa dell&#039;acqua. L&#039;attuale bocchetta per tubo diritto \u00e8 stata sostituita con una angolata a 90\u00b0.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_innen.jpg\" alt=\"\" class=\"wp-image-1873\" srcset=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_innen.jpg 800w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_innen-300x225.jpg 300w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_innen-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Collegamento del tubo tramite portagomma angolato a 90\u00b0<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Poich\u00e9 la presa dell&#039;acqua standard \u00e8 collegata a un raccordo a compressione sul connettore assemblato, anche questo collegamento ha dovuto essere smontato e sostituito con un collegamento per aria compressa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"600\" height=\"590\" src=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_aussen.jpg\" alt=\"\" class=\"wp-image-1874\" srcset=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_aussen.jpg 600w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Wasserdose_aussen-300x295.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Scatola di derivazione acqua modificata<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">L&#039;interruttore non necessita di collegamento per un sistema di pressione, altrimenti viene utilizzato per accendere manualmente la pompa dell&#039;acqua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resta infine da prevedere la ventilazione con una zanzariera e una idonea <a href=\"https:\/\/www.amazon.de\/gp\/product\/B0754GQ7K4\/ref=ppx_yo_dt_b_asin_title_o08_s00?ie=UTF8&amp;psc=1\" target=\"_blank\" rel=\"noreferrer noopener\">Griglia di scarico<\/a> coprire.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_geschlossen-768x1024.jpg\" alt=\"\" class=\"wp-image-1865\" srcset=\"https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_geschlossen-768x1024.jpg 768w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_geschlossen-225x300.jpg 225w, https:\/\/csiag.eu\/wp-content\/uploads\/2022\/06\/Service_Klappe_geschlossen.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Copertura di ventilazione nello sportello di servizio<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:34px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">ps Se hai bisogno di supporto personale nell&#039;implementazione a pagamento, sei il benvenuto&nbsp;<a href=\"https:\/\/csiag.eu\/it\/servizio-di-consulenza\/\">biglietteria<\/a>&nbsp;Fare!<\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Momento della lettura<\/span> <span class=\"rt-time\"> 4<\/span> <span class=\"rt-label rt-postfix\">minuti<\/span><\/span>Tutti conoscono la toilette a cassetta Thetford, i problemi di smaltimento, le cassette troppo piccole e i pi\u00f9 audaci ne acquistano addirittura diverse per prolungare gli intervalli di smaltimento. La toilette separata promette soluzioni semplici e prive di odori, facili da sostituire e a bassa manutenzione. Alcuni sono dotati di un agitatore meccanico ad azionamento manuale. Anche in questo caso vengono offerti set semplici e quindi economici, composti da due contenitori e...&nbsp;<a href=\"https:\/\/csiag.eu\/it\/blog\/2022\/06\/14\/austausch-thetford-kassetten-toilette-gegen-separette-trenntoilette\/\" rel=\"bookmark\">Leggi tutto \"<span class=\"screen-reader-text\">Sostituzione della toilette a cassetta Thetford con una toilette separabile Separatte<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[341],"tags":[1017,1026,1020,989,1024,1016,1018,1019,1025,1023,1014,1011,1015,1012,1013,1022,1021],"class_list":["post-1857","post","type-post","status-publish","format-standard","hentry","category-austausch-thetford-kassetten-toilette-gegen-separette-trenntoilette","tag-abluft","tag-abluftgitter","tag-airfit","tag-ausbau","tag-druckluftverbindung","tag-einbau","tag-luefter","tag-lueftermotor","tag-schalter","tag-schlauchtuelle","tag-separette","tag-thetford","tag-tiny","tag-toplette","tag-trentoilette","tag-wasserschlauch","tag-wassersteckdose"],"modified_by":"Achim Goerner","_links":{"self":[{"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/posts\/1857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/comments?post=1857"}],"version-history":[{"count":0,"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/posts\/1857\/revisions"}],"wp:attachment":[{"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/media?parent=1857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/categories?post=1857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/csiag.eu\/it\/wp-json\/wp\/v2\/tags?post=1857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}