{"id":11640,"date":"2025-11-19T18:47:27","date_gmt":"2025-11-19T18:47:27","guid":{"rendered":"https:\/\/csiag.eu\/?p=11640"},"modified":"2025-12-10T11:50:50","modified_gmt":"2025-12-10T11:50:50","slug":"planovanie-cisterien-na-pitnu-vodu","status":"publish","type":"post","link":"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/","title":{"rendered":"Pl\u00e1novanie cisterien na pitn\u00fa vodu"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Wasser-Analyse_und_Grenzwerte\" >Wasser-Analyse und Grenzwerte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Wasserharte\" >Wasserh\u00e4rte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Wasserenthartung\" >Wasserenth\u00e4rtung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Impfkristallisations-Technologien\" >Impfkristallisations-Technologien<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#TAC\" >TAC<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#NAC\" >NAC<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#MAC\" >MAC<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Anbieter_von_Systemen_mit_Impfkristallisation\" >Anbieter von Systemen mit Impfkristallisation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Ergiebigkeit_der_Quelle\" >Ergiebigkeit der Quelle<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Auswahl_der_Forderpumpe\" >Auswahl der F\u00f6rderpumpe<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Ventile\" >Ventile<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/#Fullstands-Messung\" >F\u00fcllstands-Messung<\/a><\/li><\/ul><\/nav><\/div>\n<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesedauer<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>\n<p class=\"wp-block-paragraph\">Die Planung von Trinkwasser-Zisternen umfasst mehrere physikalische Gegebenheiten, die es zu ber\u00fccksichtigen gilt, will man mit m\u00f6glichst geringem Aufwand die gew\u00fcnschte Trinkwasser-Qualit\u00e4t und F\u00f6rderleistung erzielen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wasser-Analyse_und_Grenzwerte\"><\/span><strong>Wasser-Analyse und Grenzwerte<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zun\u00e4chst ist von jeder Wasserquelle eine Laboranalyse zu fertigen, mittels derer die Wasserwerte mit den geltenden Grenzwerten verglichen werden, um ggf. gezielt Ma\u00dfnahmen zur Einhaltung derselben ergreifen zu k\u00f6nnen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acrylamid 0,10 \u03bcg\/l<\/li>\n\n\n\n<li>Antimon 10 \u03bcg\/l<\/li>\n\n\n\n<li>Arsen 10 \u03bcg\/l<\/li>\n\n\n\n<li>Benzol 1,0 \u03bcg\/l<\/li>\n\n\n\n<li>Benzo(a)pyren 0,010 \u03bcg\/l<\/li>\n\n\n\n<li>Bisphenol A 2,5 \u03bcg\/l<\/li>\n\n\n\n<li>Bor 1,5 mg\/l<\/li>\n\n\n\n<li>Bromat 10 \u03bcg\/l<\/li>\n\n\n\n<li>Cadmium 5,0 \u03bcg\/l<\/li>\n\n\n\n<li>Chlorat 0,25 mg\/l<\/li>\n\n\n\n<li>Chlorit 0,25 mg\/l<\/li>\n\n\n\n<li>Chrom 25 \u03bcg\/l<\/li>\n\n\n\n<li>Kupfer 2,0 mg\/l<\/li>\n\n\n\n<li>Cyanid 50 \u03bcg\/l<\/li>\n\n\n\n<li>1,2-Dichlorethan 3,0 \u03bcg\/l<\/li>\n\n\n\n<li>Epichlorhydrin 0,10 \u03bcg\/l<\/li>\n\n\n\n<li>Fluorid 1,5 mg\/l<\/li>\n\n\n\n<li>Halogenessigs\u00e4uren (HAAs) 60 \u03bcg\/l<\/li>\n\n\n\n<li>Blei 5 \u03bcg\/l<\/li>\n\n\n\n<li>Quecksilber 1,0 \u03bcg\/l<\/li>\n\n\n\n<li>Microcystin-LR 1,0 \u03bcg\/l<\/li>\n\n\n\n<li>Nickel 20 \u03bcg\/l<\/li>\n\n\n\n<li>Nitrat 50 mg\/l<\/li>\n\n\n\n<li>Nitrit 0,50 mg\/l<\/li>\n\n\n\n<li>Pestizide 0,10 \u03bcg\/l<\/li>\n\n\n\n<li>Pestizid gesamt 0,50 \u03bcg\/l<\/li>\n\n\n\n<li>PFAS gesamt 0,50 \u03bcg\/l<\/li>\n\n\n\n<li>Summe der PFAS 0,10 \u03bcg\/l<\/li>\n\n\n\n<li>Polyzyklische aromatische Kohlenwasserstoffe 0,10 \u03bcg\/l<\/li>\n\n\n\n<li>Selen 20 \u03bcg\/l<\/li>\n\n\n\n<li>Tetrachlorethen und Trichlorethen 10 \u03bcg\/l<\/li>\n\n\n\n<li>Trihalogenmethane gesamt 100 \u03bcg\/l<\/li>\n\n\n\n<li>Uran 30 \u03bcg\/l<\/li>\n\n\n\n<li>Vinylchlorid 0,50 \u03bcg\/l<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wasserharte\"><\/span><strong>Wasserh\u00e4rte<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wasserh\u00e4rte repr\u00e4sentiert den Gehalt von Calciumcarbonat (CaCO\u2083) in <strong>mmol\/l<\/strong>, <strong>ppm<\/strong> oder <strong>mg\/l<\/strong>  (1 mmol\/l = 1 ppm\/l = 1 mg\/l) Erdalkali-Ionen gem\u00e4\u00df dem internationalen Einheitssystem SI (<em>Syst\u00e8me International d&#8217;Unit\u00e9s<\/em>), veraltet auch noch in \u00b0dH (deutsche H\u00e4rte 1 \u00b0dH entspricht 0,1783 mml\/l), angegeben.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>weiches Wasser -&gt; kleiner 8,4 \u00b0dH, entsprechend kleiner 1,5 mmoll<\/li>\n\n\n\n<li>mittel -&gt; 8,4 .. 14 \u00b0dH, entsprechend 1,5 .. 2,5 mmol\/l<\/li>\n\n\n\n<li>hartes Wasser -&gt; gr\u00f6\u00dfer 14 \u00b0dH, entsprechend gr\u00f6\u00dfer 2,5 mmol\/l<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wasserh\u00e4rte zeigt sich u.a. in Kalkablagerungen in Leitungen, auf von Wasser benetzten Oberfl\u00e4chen und im Verbrauch von mehr Waschmittel je kalkhaltiger, mithin h\u00e4rter das Wasser ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wasserenthartung\"><\/span><strong>Wasserenth\u00e4rtung<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wasserenth\u00e4rtung kann auf zwei Wegen vorgenommen werden, so durch:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ionentauscher<\/strong> (hier wird Wasser durch einen mit Natrium-Ionen ges\u00e4ttigten Harzfilter geleitet, wobei ein Austausch von im Wasser gel\u00f6sten Calcium- und Magnesium-Ionen gegen die Natrium-Ionen des Harzes stattfindet.<br>Ionentauscher sind je nach Durchflussmenge fr\u00fcher oder sp\u00e4ter mit Calcium- und Magnesium-Ionen ges\u00e4ttigt und m\u00fcssen dann mit einer hochkonzentrierten Kochsalz-L\u00f6sung (NaCl) gesp\u00fclt, regeneriert werden. Danach k\u00f6nnen sie wieder Calcium- und Magnesium-Ionen aufnehmen und entsprechend Natrium-Ionen abgeben.<br>Derlei Anlagen ben\u00f6tigen im Laufe eines Jahres je nach Durchsatz gro\u00dfe Mengen, ein nach <em>EN 973 Typ <\/em>A zertifiziertes, hochreines Salz mit einer Reinheit \u00fcber 99,5 %.<br>Nachteilig ist die Anreicherung des Wassers mit Natrium, womit der Gedanke &#8222;natriumarmen&#8220; Trinkwassers konterkariert wird. Ebenso nat\u00fcrlich die wiederkehrenden Kosten f\u00fcr das Regenerations-Salz, wie den damit verbundenen Wartungsaufwand.<\/li>\n\n\n\n<li><strong>Umkehrosmose<\/strong>, indem das Wasser mit hohem Druck durch 0,00001 \u00b5m feine Filterporen gepresst wird. Nachteilig ist allerdings, dass das resultierende Wasser keinerlei Mineralstoffe mehr enth\u00e4lt und somit re-mineralisiert werden muss, um f\u00fcr den menschlichen Organismus wieder verwertbar zu werden.<br>Nachteilig sind die regelm\u00e4\u00dfig wiederkehrenden Kosten f\u00fcr die Osmosemembran (Filterkartusche) und das &#8222;Wasser&#8220;, das bei der Umkehrosmose anf\u00e4llt und bis zu 50% zus\u00e4tzlichen Wasserverbrauch betragen kann.<\/li>\n\n\n\n<li><strong>Destillation<\/strong>, was ebenfalls in Wasser ohne jeglichen Mineralstoffgehalt m\u00fcndet und damit f\u00fcr den Menschen gesundheitlich kontraproduktiv ist.<br>Nachteilig ist zus\u00e4tzlich der hohe Energieaufwand.<\/li>\n\n\n\n<li><strong>Impfkristallisation<\/strong>, bei der mittels eines Katalysators (gef\u00fcllt mit speziell beschichteten Keramik oder Polymer-K\u00fcgelchen, an denen Calcium- und Carbonat-Ionen andocken und auskristallisieren) der das Kalkablagerungen verursachende Calcit in nadelf\u00f6rmige, nicht mehr anhaftende Aragonit-Kristalle umwandelt.<br>Das Wasser beinhaltet nach wie vor alle Mineralien, inklusive &#8222;Kalk&#8220; in Form der Aragonit-Kristalle).<br>F\u00fcr den Organismus ist dieses Wasser vollst\u00e4ndig nutzbar.<br>Solche Ger\u00e4te haben Standzeiten von \u00fcber zehn Jahren, je nach Durchsatz und Dimensionierung. Sie werden in die Hauptzuleitung der Hauswasserversorgung nach dem Wasserz\u00e4hler eingeschleift.<br><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impfkristallisations-Technologien\"><\/span>Impfkristallisations-Technologien<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wasserh\u00e4rte \u00e4ndert sich bei keiner der nachfolgenden Technologien. Allerdings lagert sich Kalk nur noch stark vermindert ab, da das CaCO<sub>3<\/sub> bereits in stabilen feinen Mikro- oder sehr feinen Nanokristallen gebunden vorliegt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"TAC\"><\/span>TAC<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Template Assisted Crystallization<\/em> &#8211; Tr\u00e4ger des Kristallisationskeimes ist ein festes Medium, z.B. Harz oder Granulat. Auf diesen bilden sich beim Durchstr\u00f6men des Wassers Calciumcarbonat-Kristalle, die sich umgehend vom Medium abl\u00f6sen und mit dem Awasser fortgeleitet werden.<br>Ideal bei geringerem Durchfluss, da die Bildung der Mikro- im Vergleich zu Nanokristallen beim NAC-Verfahren mehr Zeit beansprucht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"NAC\"><\/span>NAC<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Nucleation Assisted Crystallization<\/em> &#8211; prinzipiell identisch mit dem TAC-Verfahren, jedoch werden hier Nano- statt Microkristalle erzeugt. D.h. die Partikelzahl ist gr\u00f6\u00dfer, die Kristalle kleiner.<br>Vorteilhaft, wenn hoher Durchfluss gefordert ist, da die Kontaktzeit zum Medium deshalb k\u00fcrzer ist und die Kristallbildung systembedingt schneller als beim TAC-Verfahren abl\u00e4uft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"MAC\"><\/span>MAC<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Media Assisted Crystallization<\/em> &#8211; fasst beide Verfahren, TAC und NAC, unter einem \u00dcberbegriff zusammen. Die Bezeichnung MAC wird meist dann verwendet, wenn eigene Technologien in anwendung kommen, die sich von \u00fcblichen TAC-\/NAC-Verfahrenstechnolgien unterscheiden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Anbieter_von_Systemen_mit_Impfkristallisation\"><\/span>Anbieter von Systemen mit Impfkristallisation<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie immer gilt es die Spreu vom Weizen zu trennen, sprich: welcher Hersteller behauptet nicht nur, sondern belegt auch die Funktion seiner Produkte mit entsprechenden Zertifikaten unabh\u00e4ngiger Pr\u00fcfstellen und \/ oder Studien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kontaktzeit des durchstr\u00f6menden Wassers ist, wi evor erw\u00e4hnt, funktional bedeutsam, weshalb die Datenbl\u00e4tter der einzelnen Produkte hinsichtlich dieses Kriteriums gesondert zu bewerten sind und die Gesamtanlage darauf abszustimmen ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nachfolgende Hersteller fallen hier positiv auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.scalestopplus.com\/technology.html\" target=\"_blank\" rel=\"noreferrer noopener\">ScaleStop<\/a> &#8211; <a href=\"mailto:support@scalestopplus.com\">support@scalestopplus.com<\/a><br>Unabh\u00e4ngige Tests der <a href=\"https:\/\/scalestopplus.com\/alternatives-to-domestic-ion-exchange-water-softeners.html\" target=\"_blank\" rel=\"noreferrer noopener\">Arizona State University<\/a> und DVGW (W512 aus 2013) belegen die Wirksamkeit mit jeweils 99%<\/li>\n\n\n\n<li><a href=\"https:\/\/www.watertechgroup.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">Water Tech<\/a> &#8211; <a href=\"mailto:info@watertechgroup.com\">info@watertechgroup.com<\/a><br>bewirbt sein Produkt <a href=\"https:\/\/www.watertechgroup.com\/images\/Datasheets\/equipment\/softeners-systems\/Water-Tech-SCALE-SAFE-Tech-Description.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Scale-Safe<\/a> mit einer 99,9-prozentigen Wirksamkeit<\/li>\n\n\n\n<li><a href=\"https:\/\/www.aqon-pure.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aqon Pure<\/a> &#8211; <a href=\"mailto:info@aqon-pure.com\">info@aqon-pure.com<\/a><br>belegt die Wirksamkeit ihres Systems mit zwei Studien: der <a href=\"https:\/\/cdn.prod.website-files.com\/65016903de2eec3e906d6c6c\/66e94d8ce9395c7575fed121_Hohenstein_24.8.6.0005_AQON.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Hohenstein Innovations gGmbH<\/a> und der GSA (<a href=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0840\/0581\/4600\/files\/aqon-pure-wirkung-gsa-uebersicht.pdf?v=1730200527\" target=\"_blank\" rel=\"noreferrer noopener\">Link 1<\/a>, <a href=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0840\/0581\/4600\/files\/aqon-pure-wirkung-gsa-kurzbericht.pdf?v=1730200500\" target=\"_blank\" rel=\"noreferrer noopener\">Link 2<\/a>, <a href=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0840\/0581\/4600\/files\/aqon-pure-wirkung-gsa-bericht.pdf?v=1730200468\" target=\"_blank\" rel=\"noreferrer noopener\">Link 3<\/a>)<\/li>\n\n\n\n<li><a href=\"https:\/\/www.watts.eu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Watts<\/a> &#8211; <a href=\"mailto:info@wattsindustries.it\">info@wattsindustries.it<\/a><br>bietet eine Produktreihe unter der Bezeichnung <a href=\"https:\/\/www.watts.eu\/en\/products\/eu\/anti-scale-system-oneflow\" target=\"_blank\" rel=\"noreferrer noopener\">One-Flow<\/a> an<\/li>\n\n\n\n<li><a href=\"https:\/\/crystalwash.fr\" target=\"_blank\" rel=\"noreferrer noopener\">Crystal Wash<\/a> &#8211; <a href=\"mailto:clean@crystalwash.fr\">clean@crystalwash.fr<\/a><br>beschr\u00e4nkt sich auf eine <a href=\"https:\/\/crystalwash.fr\/crystal-wash-ultra-pure-wash-system\/softners\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wirksamkeitsangabe von 88 .. 97 %<\/a> und bezieht sich auf die generell durch DVGW-W512 ausgewiesene Effizenz des TAC-Verfahrens<br><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ergiebigkeit_der_Quelle\"><\/span><strong>Ergiebigkeit der Quelle<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei einer vorhandenen oder geplanten Brunnenbohrung sind die Parameter Durchfluss- und Entnahmerate, neben anderen Parametern in der Berechnung der zu entnehmenden Grundwassermenge in der Zeiteinheit elementar. Die Erl\u00e4uterung, samt Berechnung findet sich sehr anschaulich auf dieser <a href=\"https:\/\/www.grundwasser.net\/\" target=\"_blank\" rel=\"noopener\">Webseite<\/a>.<br><br>Die Entnahme von Wasser aus einem Fluss ist oft genehmigungspflichtig und wird mengenm\u00e4\u00dfig begrenzt festgelegt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Auswahl_der_Forderpumpe\"><\/span><strong>Auswahl der F\u00f6rderpumpe<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Tiefbrunnenpumpe dient der F\u00f6rderung von Grundwasser aus Tiefen zwischen 8 und 90 Metern. Zu beachten ist, dass die Entnahmeh\u00f6he und Pumpentiefe (Ansaugtiefe) addiert die Gesamtf\u00f6rderh\u00f6he ergeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anwendungs-<em>Beispiel<\/em>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Pumpentiefe (Saugkorb) 20 m + h\u00f6chster Entnahmepunkt 30 m = 50 m betr\u00e4gt die gesamte F\u00f6rderh\u00f6he der Tiefbrunnenpumpe<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allerdings sind, neben der reinen H\u00f6hendifferenz, auch Reibungsverluste der Leitungsf\u00fchrung (Rauhigkeit des Rohres, Formst\u00fccke, etc. = dynamischer Kopf) zu ber\u00fccksichtigen. Diese m\u00fcssen entsprechend bei der Pumpenauswahl aufgeschlagen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ausgehend von einer Pumpenleistung von 3.000 l\/h (Q = 3\/3600 m<sup>3<\/sup>\/s =&nbsp;0,0008333333333333333 m<sup>3<\/sup>\/s), unter der Verwendung von z.B. DN65 (D = 0,0752) PE\/HDPE-Rohr mit einer Rauhigkeit lt. Datenblatt von \u03b5 = 1,5 \u00b5m = 1,5 \u00d7 10\u207b\u2076 m, der kinematische Viskosit\u00e4t von Wasser von \u2248 1\u00b710<sup>-6<\/sup> m\u00b2\/s, sowie einer Dichte \u03c1 = 1000 kg\/m<sup>3<\/sup> und Flie\u00dfgeschwindigkeit von g = 9,81 m\/s<sup>2<\/sup>, sowie Ber\u00fccksichtigung der \u00c4quivalente von Fittingen, etc. durch das kalkulierte 1,2-Fache der Leitungsl\u00e4nge von 200 m, entsprechend 240 m und zu \u00fcberwindendem H\u00f6henunterschied von H<sub>s<\/sub> 50 m (statischer Kopf) bei einer mittleren Erdbeschleunigung von g = 9,81 m\/s<sup>2<\/sup> (als Konstante), ergibt sich folgende Rechnung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Querschnitt DN65<\/strong><br>A = ( \u03c0 \u22c5 D<sup>2<\/sup> ) : 4 = ( \u03c0 \u22c5 0,0752 <sup>2<\/sup> ) : 4 = 0,004417865&nbsp;m<sup>2<\/sup><\/li>\n\n\n\n<li><strong>Str\u00f6mungsgeschwindigkeit<\/strong><br>v = Q : A = 0,0008333333333333333 m<sup>3<\/sup>\/s : 0,004417865&nbsp;m<sup>2<\/sup> = 0,1886280807&nbsp;m\/s<\/li>\n\n\n\n<li><strong>Reynoldszahl<\/strong> (Kennzahl, niedrig = laminare, hoch = turbulente Str\u00f6mung)<br>Re = \u03c5D : v = ( 0,1886280807015056 \u22c5 0,0752 ) : ( 1\u22c510\u22126&nbsp;m<sup>2<\/sup>\/s ) = 14147,10605261292&nbsp;m<sup>2<\/sup>\/s<\/li>\n\n\n\n<li><strong>Rohrreibungsbeiwert<\/strong> (Swamee-Jain)<br>f = 0,25 : [ log<sub>10<\/sub> ( (\u03b5 : ( 3,7 \u22c5 D )) + ( 5,74 : Re<sup>0,9<\/sup> ) ) ]<sup>2<\/sup><br>f = 0,25 : [ log<sub>10<\/sub> ( 5,405405405405405 \u00d7 10<sup>-6<\/sup> + 0,000728728 ) ]<sup>2<\/sup><br>f = 0,25 : [ log<sub>10<\/sub> ( 0,0007341334054054 ) ]<sup>2<\/sup><br>f = 0,25 : [ \u22123,134490 ]<sup>2<\/sup><br>f = 0,25 : 9,825866 = 0,028256663933258565<\/li>\n\n\n\n<li><strong>Rohrreibungsverlust<\/strong> (Darcy-Weisbach)<br>h<sub>f&nbsp;<\/sub> = f \u22c5 ( L : D ) \u22c5 ( v<sup>2<\/sup> : 2g )<br>h<sub>f&nbsp;<\/sub> = f \u22c5 ( 240 : 0,075 ) \u22c5 ( 0,1886280807015056<sup>2<\/sup> : 2 \u22c5 9,81 )<br>h<sub>f&nbsp;<\/sub> = f \u22c5 ( 3.200 ) \u22c5 ( 0,001813634&nbsp;m )<br>h<sub>f&nbsp;<\/sub> = 0,028256663933258565 \u22c5 5,803629 = \u2248 0,1639776104&nbsp;m<\/li>\n\n\n\n<li><strong>\u00c4quivalenter Formst\u00fcckverlust<\/strong><br>(identische Fommel, statt L (Rohrl\u00e4nge) wird L<sub>eq<\/sub> (mit 10 m gesetzt)<br>h<sub>eq<\/sub> = f \u22c5 ( L<sub>eq<\/sub> : D ) \u22c5 ( v<sup>2<\/sup> : 2g ) = \u22480,0068324004&nbsp;m<\/li>\n\n\n\n<li><strong>Gesamtf\u00f6rderh\u00f6he<\/strong><br>H<sub>tot<\/sub> = H<sub>s<\/sub> + h<sub>f&nbsp;<\/sub> + h<sub>eq<\/sub><br>H<sub>tot<\/sub> = 50,0 m + 0,1639776104&nbsp;m + 0,0068324004&nbsp;m = \u224850,1708100&nbsp;m<\/li>\n\n\n\n<li><strong>Druck am Ausgang der Pumpe<\/strong><br>p = \u03c1gH<sub>tot<\/sub><br>p = 1000\u22c59,81\u22c550,1708100108 = 492175.6462064206&nbsp;Pa<br>p = 492175.6462064206&nbsp;Pa : 10.000 = 4,921756462064206&nbsp;bar<\/li>\n\n\n\n<li><strong>Hydraulische Pumpen-Leistung<\/strong><br>P<sub>h\u200b<\/sub> = \u03c1gQH<sub>tot<\/sub><br>P<sub>h\u200b<\/sub> = 1000 \u22c5 9,81 \u22c5 0,0008333333333333333 \u22c5 50,1708100108 = 410,1463718386839&nbsp;W<\/li>\n\n\n\n<li><strong>Elektrische Motorleistung<\/strong>&nbsp;P<sub>motor\u200b&nbsp;<\/sub>bei Wirkungsgrad \u03b7 = 0,65<br>P<sub>motor<\/sub>\u200b = Ph\u200b\u200b : \u03b7<br>P<sub>motor<\/sub>\u200b = 410,1463718386839 : 0,65 = 630,9944182133598&nbsp;W<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nominell erbringt eine Pumpe mit rund 630 W die erforderliche Leistung. In der Praxis geht man, mit einem 80-prozentigen Aufschhlag als Sicherheitsreserve, also von etwa 1,1 kW aus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ventile\"><\/span>Ventile<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn jede Zisterne im Verbund einzeln trennbar sein soll, was im Falle von bei Wartungsarbeiten oder Leckagen sinnvoll ist, ben\u00f6tigt man f\u00fcr jede Zisterne ein Absperr- und R\u00fcckschlagventil, sowie ein Sp\u00fcl-, bzw. Entleerungsventil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motorisch betriebene Ventile sollten \u00fcber die M\u00f6glichkeit einer manuellen (Not-)Bet\u00e4tigung verf\u00fcgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle Komponenten m\u00fcssen bei Trinkwasser-Anforderung WRAS\/DVGW-konform ausgelegt sein (EPDM-Sitz und NBR-Membran). Montageflansche f\u00fcr die Anbindung von Aktuatoren m\u00fcssen gem\u00e4\u00df ISO 5211, Motorflansche entsprechend ISO5211 F05\/F07 ausgelegt sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Leckrate sollte gem\u00e4\u00df <strong>Klasse VI<\/strong> sein, was absolute (blasenfreie) Dichtigkeit bedeutet, mithin einer Leckrate von Null entspricht. Alle Ventilen mit (PTFE-) \/ EPDM-Sitz erf\u00fcllen diese Forderung.<br>Metallsitze erreichen nur Klasse IV: eine Leckrate von 10 ml\/min unter Pr\u00fcfdruck ist erlaubt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ob 230 V AC- oder 24 V DC-(Batterie-)Betrieb der Aktuatoren entscheidet die Forderung einer automatisierten Bedienbarkeit auch bei Ausfall des \u00f6ffentlichen Strom-Versorgungsnetzes.<br>Alle elektrischen Komponenten m\u00fcssen bei, der Witterung ausgesetzten, Anlagen nach <strong>IP65<\/strong> (staubdicht, Schutz gegen Strahlwasser), besser <strong>IP67<\/strong> ( Staubdicht, Schutz gegen kurzzeitiges Untertauchen) zugelassen sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motorisch betriebene Ventile m\u00fcssen \u00fcber Endschalter, idealerweise eine Ansteuerung \u00fcber 0 .. 10 V, resp. 4 .. 20 mA verf\u00fcgen, wenn andere Positionen als offen \/ geschlossen angesteuert werden sollen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Fullstands-Messung\"><\/span>F\u00fcllstands-Messung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die F\u00fcllstands\u00fcberwachung bieten sich Ultraschall- und Drucksensoren an. W\u00e4hrend Drucksensoren, am Zisternenboden positioniert, st\u00e4ndig Wasser ausgesetzt sind, ist die Ultraschall-Messung ber\u00fchrungslos: Der Sensor wird am oder unter dem Zisternendeckel montiert und ist damit schnell zug\u00e4nglich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Industrielle Ultraschallsensoren geben als Signal einen Strom von 4 .. 20 mA aus, der \u00fcber enen kalibrierten IU-Wandler (Strom zu Spannung) eine messwertabh\u00e4ngige Spannung erzeugt, die \u00fcber einen Mikrokontroller ausgewertet und als Messwert, in Liter, Kubikmeter oder Prozent umgerechnet, angezeigt wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allerdings steigen die Preise f\u00fcr Ultraschallsensoren analog der zunehmenden Reichweite bis in den vierstelligen Euro-Bereich. Sensoren mit bis zu 2,2 m Messdistanz liegen um die <a href=\"https:\/\/autosen.com\/de\/Positionssensoren\/Ultraschallsensoren\/Ultraschallsensor-AU007\" target=\"_blank\" rel=\"noreferrer noopener\">200 Euro<\/a>, was die Zisternentiefe auf etwa 2 m begrenzt, soll das Budget nicht \u00fcberstrapaziert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">\u010cas \u010d\u00edtania<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">z\u00e1pisnice<\/span><\/span>Die Planung von Trinkwasser-Zisternen umfasst mehrere physikalische Gegebenheiten, die es zu ber\u00fccksichtigen gilt, will man mit m\u00f6glichst geringem Aufwand die gew\u00fcnschte Trinkwasser-Qualit\u00e4t und F\u00f6rderleistung erzielen. Wasser-Analyse und Grenzwerte Zun\u00e4chst ist von jeder Wasserquelle eine Laboranalyse zu fertigen, mittels derer die Wasserwerte mit den geltenden Grenzwerten verglichen werden, um ggf. gezielt Ma\u00dfnahmen zur Einhaltung derselben ergreifen&hellip;&nbsp;<a href=\"https:\/\/csiag.eu\/sk\/blog\/2025\/11\/19\/planung-von-trinkwasser-zisternen\/\" rel=\"bookmark\">\u010c\u00edta\u0165 viac \"<span class=\"screen-reader-text\">Pl\u00e1novanie cisterien na pitn\u00fa vodu<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-11640","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"modified_by":"Achim Goerner","_links":{"self":[{"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/posts\/11640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/comments?post=11640"}],"version-history":[{"count":0,"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/posts\/11640\/revisions"}],"wp:attachment":[{"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/media?parent=11640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/categories?post=11640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/csiag.eu\/sk\/wp-json\/wp\/v2\/tags?post=11640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}